{"id":38604,"date":"2016-11-22T11:54:45","date_gmt":"2016-11-22T09:54:45","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38604"},"modified":"2016-11-22T11:54:45","modified_gmt":"2016-11-22T09:54:45","slug":"enjil-al-yawm-fr-221116","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-221116\/","title":{"rendered":"Enjil Al Yawm FR- 22\/11\/16"},"content":{"rendered":"<p><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc 21,5-11. <\/strong><br \/>\n<strong>En ce temps-l\u00e0, comme certains parlaient du Temple, des belles pierres et des ex-voto qui le d\u00e9coraient, J\u00e9sus leur d\u00e9clara :<\/strong><br \/>\n<strong>\u00ab Ce que vous contemplez, des jours viendront o\u00f9 il n\u2019en restera pas pierre sur pierre : tout sera d\u00e9truit. \u00bb<\/strong><br \/>\n<strong>Ils lui demand\u00e8rent : \u00ab Ma\u00eetre, quand cela arrivera-t-il ? Et quel sera le signe que cela est sur le point d\u2019arriver ? \u00bb<\/strong><br \/>\n<strong>J\u00e9sus r\u00e9pondit : \u00ab Prenez garde de ne pas vous laisser \u00e9garer, car beaucoup viendront sous mon nom, et diront : \u201cC\u2019est moi\u201d, ou encore : \u201cLe moment est tout proche.\u201d Ne marchez pas derri\u00e8re eux !<\/strong><br \/>\n<strong>Quand vous entendrez parler de guerres et de d\u00e9sordres, ne soyez pas terrifi\u00e9s : il faut que cela arrive d\u2019abord, mais ce ne sera pas aussit\u00f4t la fin. \u00bb<\/strong><br \/>\n<strong>Alors J\u00e9sus ajouta : \u00ab On se dressera nation contre nation, royaume contre royaume.<\/strong><br \/>\n<strong>Il y aura de grands tremblements de terre et, en divers lieux, des famines et des \u00e9pid\u00e9mies ; des ph\u00e9nom\u00e8nes effrayants surviendront, et de grands signes venus du ciel. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 21,5-11. En ce temps-l\u00e0, comme certains parlaient du Temple, des belles pierres et des ex-voto qui le d\u00e9coraient, J\u00e9sus leur d\u00e9clara : \u00ab [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38604","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38604"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38604\/revisions"}],"predecessor-version":[{"id":38607,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38604\/revisions\/38607"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}