{"id":38497,"date":"2016-11-11T08:11:28","date_gmt":"2016-11-11T06:11:28","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38497"},"modified":"2016-11-11T08:11:28","modified_gmt":"2016-11-11T06:11:28","slug":"enjil-al-yawm-it-111116","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-it-111116\/","title":{"rendered":"Enjil Al Yawm IT- 11\/11\/16"},"content":{"rendered":"<p><strong>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 17,26-37. <\/strong><br \/>\n<strong>In quel tempo, Ges\u00f9 disse ai suoi discepoli: \u00abCome avvenne al tempo di No\u00e8, cos\u00ec sar\u00e0 nei giorni del Figlio dell&#8217;uomo: <\/strong><br \/>\n<strong>mangiavano, bevevano, si ammogliavano e si maritavano, fino al giorno in cui No\u00e8 entr\u00f2 nell&#8217;arca e venne il diluvio e li fece perire tutti. <\/strong><br \/>\n<strong>Come avvenne anche al tempo di Lot: mangiavano, bevevano, compravano, vendevano, piantavano, costruivano; <\/strong><br \/>\n<strong>ma nel giorno in cui Lot usc\u00ec da S\u00f2doma piovve fuoco e zolfo dal cielo e li fece perire tutti. <\/strong><br \/>\n<strong>Cos\u00ec sar\u00e0 nel giorno in cui il Figlio dell&#8217;uomo si riveler\u00e0. <\/strong><br \/>\n<strong>In quel giorno, chi si trover\u00e0 sulla terrazza, se le sue cose sono in casa, non scenda a prenderle; cos\u00ec chi si trover\u00e0 nel campo, non torni indietro. <\/strong><br \/>\n<strong>Ricordatevi della moglie di Lot. <\/strong><br \/>\n<strong>Chi cercher\u00e0 di salvare la propria vita la perder\u00e0, chi invece la perde la salver\u00e0. <\/strong><br \/>\n<strong>Vi dico: in quella notte due si troveranno in un letto: l&#8217;uno verr\u00e0 preso e l&#8217;altro lasciato; <\/strong><br \/>\n<strong>due donne staranno a macinare nello stesso luogo: <\/strong><br \/>\n<strong>l&#8217;una verr\u00e0 presa e l&#8217;altra lasciata\u00bb. <\/strong><br \/>\n<strong>Allora i discepoli gli chiesero: \u00abDove, Signore?\u00bb. Ed egli disse loro: \u00abDove sar\u00e0 il cadavere, l\u00e0 si raduneranno anche gli avvoltoi\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 17,26-37. In quel tempo, Ges\u00f9 disse ai suoi discepoli: \u00abCome avvenne al tempo di No\u00e8, cos\u00ec sar\u00e0 nei giorni del Figlio dell&#8217;uomo: mangiavano, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38497","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38497"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38497\/revisions"}],"predecessor-version":[{"id":38502,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38497\/revisions\/38502"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}