{"id":38449,"date":"2016-11-07T08:20:38","date_gmt":"2016-11-07T06:20:38","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38449"},"modified":"2016-11-07T08:20:38","modified_gmt":"2016-11-07T06:20:38","slug":"enjil-al-yawm-por-071116","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-por-071116\/","title":{"rendered":"Enjil Al Yawm POR- 07\/11\/16"},"content":{"rendered":"<p><strong>Evangelho segundo S. Lucas 17,1-6. <\/strong><br \/>\n<strong>Naquele tempo, disse Jesus aos seus disc\u00edpulos: \u00ab\u00c9 inevit\u00e1vel que haja esc\u00e2ndalos; mas ai daquele que os provoca. <\/strong><br \/>\n<strong>Melhor seria para ele que lhe atassem ao pesco\u00e7o uma m\u00f3 de moinho e o atirassem ao mar, do que ser ocasi\u00e3o de pecado para um s\u00f3 destes pequeninos. <\/strong><br \/>\n<strong>Tende cuidado. Se teu irm\u00e3o cometer uma ofensa, repreende-o, e, se ele se arrepender, perdoa-lhe. <\/strong><br \/>\n<strong>Se te ofender sete vezes num dia e sete vezes vier ter contigo e te disser: \u2018Estou arrependido\u2019, tu lhe perdoar\u00e1s\u00bb. <\/strong><br \/>\n<strong>Os Ap\u00f3stolos disseram ao Senhor: \u00abAumenta a nossa f\u00e9\u00bb. <\/strong><br \/>\n<strong>O Senhor respondeu: \u00abSe tiv\u00e9sseis f\u00e9 como um gr\u00e3o de mostarda, dir\u00edeis a esta amoreira: \u2018Arranca-te da\u00ed e vai plantar-te no mar\u2019, e ela vos obedeceria\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangelho segundo S. Lucas 17,1-6. Naquele tempo, disse Jesus aos seus disc\u00edpulos: \u00ab\u00c9 inevit\u00e1vel que haja esc\u00e2ndalos; mas ai daquele que os provoca. Melhor seria para ele que lhe atassem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38449","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38449"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38449\/revisions"}],"predecessor-version":[{"id":38454,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38449\/revisions\/38454"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}