{"id":38396,"date":"2016-11-02T08:37:55","date_gmt":"2016-11-02T06:37:55","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38396"},"modified":"2016-11-02T08:37:55","modified_gmt":"2016-11-02T06:37:55","slug":"enjil-al-yawm-it-021116","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-it-021116\/","title":{"rendered":"Enjil Al Yawm IT- 02\/11\/16"},"content":{"rendered":"<p><strong>Dal Vangelo di Ges\u00f9 Cristo secondo Matteo 25,31-46. <\/strong><br \/>\n<strong>In quel tempo, Ges\u00f9 disse ai suoi discepoli: \u00abQuando il Figlio dell&#8217;uomo verr\u00e0 nella sua gloria con tutti i suoi angeli, si sieder\u00e0 sul trono della sua gloria. <\/strong><br \/>\n<strong>E saranno riunite davanti a lui tutte le genti, ed egli separer\u00e0 gli uni dagli altri, come il pastore separa le pecore dai capri, <\/strong><br \/>\n<strong>e porr\u00e0 le pecore alla sua destra e i capri alla sinistra. <\/strong><br \/>\n<strong>Allora il re dir\u00e0 a quelli che stanno alla sua destra: Venite, benedetti del Padre mio, ricevete in eredit\u00e0 il regno preparato per voi fin dalla fondazione del mondo. <\/strong><br \/>\n<strong>Perch\u00e9 io ho avuto fame e mi avete dato da mangiare, ho avuto sete e mi avete dato da bere; ero forestiero e mi avete ospitato, <\/strong><br \/>\n<strong>nudo e mi avete vestito, malato e mi avete visitato, carcerato e siete venuti a trovarmi. <\/strong><br \/>\n<strong>Allora i giusti gli risponderanno: Signore, quando mai ti abbiamo veduto affamato e ti abbiamo dato da mangiare, assetato e ti abbiamo dato da bere? <\/strong><br \/>\n<strong>Quando ti abbiamo visto forestiero e ti abbiamo ospitato, o nudo e ti abbiamo vestito? <\/strong><br \/>\n<strong>E quando ti abbiamo visto ammalato o in carcere e siamo venuti a visitarti? <\/strong><br \/>\n<strong>Rispondendo, il re dir\u00e0 loro: In verit\u00e0 vi dico: ogni volta che avete fatto queste cose a uno solo di questi miei fratelli pi\u00f9 piccoli, l&#8217;avete fatto a me. <\/strong><br \/>\n<strong>Poi dir\u00e0 a quelli alla sua sinistra: Via, lontano da me, maledetti, nel fuoco eterno, preparato per il diavolo e per i suoi angeli. <\/strong><br \/>\n<strong>Perch\u00e9 ho avuto fame e non mi avete dato da mangiare; ho avuto sete e non mi avete dato da bere; <\/strong><br \/>\n<strong>ero forestiero e non mi avete ospitato, nudo e non mi avete vestito, malato e in carcere e non mi avete visitato. <\/strong><br \/>\n<strong>Anch&#8217;essi allora risponderanno: Signore, quando mai ti abbiamo visto affamato o assetato o forestiero o nudo o malato o in carcere e non ti abbiamo assistito? <\/strong><br \/>\n<strong>Ma egli risponder\u00e0: In verit\u00e0 vi dico: ogni volta che non avete fatto queste cose a uno di questi miei fratelli pi\u00f9 piccoli, non l&#8217;avete fatto a me. <\/strong><br \/>\n<strong>E se ne andranno, questi al supplizio eterno, e i giusti alla vita eterna\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Vangelo di Ges\u00f9 Cristo secondo Matteo 25,31-46. In quel tempo, Ges\u00f9 disse ai suoi discepoli: \u00abQuando il Figlio dell&#8217;uomo verr\u00e0 nella sua gloria con tutti i suoi angeli, si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38396","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38396"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38396\/revisions"}],"predecessor-version":[{"id":38400,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38396\/revisions\/38400"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}