{"id":38366,"date":"2016-10-31T08:12:32","date_gmt":"2016-10-31T06:12:32","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38366"},"modified":"2016-10-31T08:12:32","modified_gmt":"2016-10-31T06:12:32","slug":"enjil-al-yawm-fr-311016","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-311016\/","title":{"rendered":"Enjil Al Yawm FR- 31\/10\/16"},"content":{"rendered":"<p><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc 14,12-14. <\/strong><br \/>\n<strong>En ce temps-l\u00e0, J\u00e9sus disait aussi \u00e0 celui qui l\u2019avait invit\u00e9 : \u00ab Quand tu donnes un d\u00e9jeuner ou un d\u00eener, n\u2019invite pas tes amis, ni tes fr\u00e8res, ni tes parents, ni de riches voisins ; sinon, eux aussi te rendraient l\u2019invitation et ce serait pour toi un don en retour.<\/strong><br \/>\n<strong>Au contraire, quand tu donnes une r\u00e9ception, invite des pauvres, des estropi\u00e9s, des boiteux, des aveugles ;<\/strong><br \/>\n<strong>heureux seras-tu, parce qu\u2019ils n\u2019ont rien \u00e0 te donner en retour : cela te sera rendu \u00e0 la r\u00e9surrection des justes. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 14,12-14. En ce temps-l\u00e0, J\u00e9sus disait aussi \u00e0 celui qui l\u2019avait invit\u00e9 : \u00ab Quand tu donnes un d\u00e9jeuner ou un d\u00eener, n\u2019invite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38366","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38366"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38366\/revisions"}],"predecessor-version":[{"id":38370,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38366\/revisions\/38370"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}