{"id":38353,"date":"2016-10-29T09:31:57","date_gmt":"2016-10-29T07:31:57","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=38353"},"modified":"2016-10-29T09:31:57","modified_gmt":"2016-10-29T07:31:57","slug":"enjil-al-yawm-fr-291016","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-291016\/","title":{"rendered":"Enjil Al Yawm FR- 29\/10\/16"},"content":{"rendered":"<p><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc 14,1.7-11. <\/strong><br \/>\n<strong>Un jour de sabbat, J\u00e9sus \u00e9tait entr\u00e9 dans la maison d\u2019un chef des pharisiens pour y prendre son repas, et ces derniers l\u2019observaient.<\/strong><br \/>\n<strong>J\u00e9sus dit une parabole aux invit\u00e9s lorsqu\u2019il remarqua comment ils choisissaient les premi\u00e8res places, et il leur dit :<\/strong><br \/>\n<strong>\u00ab Quand quelqu\u2019un t\u2019invite \u00e0 des noces, ne va pas t\u2019installer \u00e0 la premi\u00e8re place, de peur qu\u2019il ait invit\u00e9 un autre plus consid\u00e9r\u00e9 que toi.<\/strong><br \/>\n<strong>Alors, celui qui vous a invit\u00e9s, toi et lui, viendra te dire : \u201cC\u00e8de-lui ta place\u201d ; et, \u00e0 ce moment, tu iras, plein de honte, prendre la derni\u00e8re place.<\/strong><br \/>\n<strong>Au contraire, quand tu es invit\u00e9, va te mettre \u00e0 la derni\u00e8re place. Alors, quand viendra celui qui t\u2019a invit\u00e9, il te dira : \u201cMon ami, avance plus haut\u201d, et ce sera pour toi un honneur aux yeux de tous ceux qui seront \u00e0 la table avec toi.<\/strong><br \/>\n<strong>En effet, quiconque s\u2019\u00e9l\u00e8ve sera abaiss\u00e9 ; et qui s\u2019abaisse sera \u00e9lev\u00e9. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 14,1.7-11. Un jour de sabbat, J\u00e9sus \u00e9tait entr\u00e9 dans la maison d\u2019un chef des pharisiens pour y prendre son repas, et ces derniers [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-38353","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=38353"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38353\/revisions"}],"predecessor-version":[{"id":38356,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/38353\/revisions\/38356"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=38353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=38353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=38353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}