{"id":34244,"date":"2015-11-06T08:26:18","date_gmt":"2015-11-06T06:26:18","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=34244"},"modified":"2015-11-06T08:26:18","modified_gmt":"2015-11-06T06:26:18","slug":"enjil-al-yawm-fr-061115","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-061115\/","title":{"rendered":"Enjil Al Yawm FR- 06\/11\/15"},"content":{"rendered":"<p><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc <span dir=\"ltr\">16,1-8.<\/span> <\/strong><br \/>\n<strong>J\u00e9sus disait encore aux disciples\u00a0: \u00ab\u00a0Un homme riche avait un g\u00e9rant qui lui fut d\u00e9nonc\u00e9 comme dilapidant ses biens. <\/strong><br \/>\n<strong>Il le convoqua et lui dit\u00a0: \u201cQu\u2019est-ce que j\u2019apprends \u00e0 ton sujet\u00a0? Rends-moi les comptes de ta gestion, car tu ne peux plus \u00eatre mon g\u00e9rant.\u201d <\/strong><br \/>\n<strong>Le g\u00e9rant se dit en lui-m\u00eame\u00a0: \u201cQue vais-je faire, puisque mon ma\u00eetre me retire la gestion\u00a0? Travailler la terre\u00a0? Je n\u2019en ai pas la force. Mendier\u00a0? J\u2019aurais honte. <\/strong><br \/>\n<strong>Je sais ce que je vais faire, pour qu\u2019une fois renvoy\u00e9 de ma g\u00e9rance, des gens m\u2019accueillent chez eux.\u201d <\/strong><br \/>\n<strong>Il fit alors venir, un par un, ceux qui avaient des dettes envers son ma\u00eetre. Il demanda au premier\u00a0: \u201cCombien dois-tu \u00e0 mon ma\u00eetre\u00a0?\u201d <\/strong><br \/>\n<strong>Il r\u00e9pondit\u00a0: \u201cCent barils d\u2019huile.\u201d Le g\u00e9rant lui dit\u00a0: \u201cVoici ton re\u00e7u\u00a0; vite, assieds-toi et \u00e9cris cinquante.\u201d <\/strong><br \/>\n<strong>Puis il demanda \u00e0 un autre\u00a0: \u201cEt toi, combien dois-tu\u00a0?\u201d Il r\u00e9pondit\u00a0: \u201cCent sacs de bl\u00e9.\u201d Le g\u00e9rant lui dit\u00a0: \u201cVoici ton re\u00e7u, \u00e9cris quatre-vingts.\u201d <\/strong><br \/>\n<strong>Le ma\u00eetre fit l\u2019\u00e9loge de ce g\u00e9rant malhonn\u00eate car il avait agi avec habilet\u00e9\u00a0; en effet, les fils de ce monde sont plus habiles entre eux que les fils de la lumi\u00e8re. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 16,1-8. J\u00e9sus disait encore aux disciples\u00a0: \u00ab\u00a0Un homme riche avait un g\u00e9rant qui lui fut d\u00e9nonc\u00e9 comme dilapidant ses biens. Il le convoqua [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-34244","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=34244"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34244\/revisions"}],"predecessor-version":[{"id":34248,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34244\/revisions\/34248"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=34244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=34244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=34244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}