{"id":34232,"date":"2015-11-05T08:38:15","date_gmt":"2015-11-05T06:38:15","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=34232"},"modified":"2015-11-05T08:38:15","modified_gmt":"2015-11-05T06:38:15","slug":"enjil-al-yawm-fr-051115","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-051115\/","title":{"rendered":"Enjil Al Yawm FR- 05\/11\/15"},"content":{"rendered":"<p><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc 15,1-10. <\/strong><br \/>\n<strong>En ce temps-l\u00e0, les publicains et les p\u00e9cheurs venaient tous \u00e0 J\u00e9sus pour l\u2019\u00e9couter.<\/strong><br \/>\n<strong>Les pharisiens et les scribes r\u00e9criminaient contre lui : \u00ab Cet homme fait bon accueil aux p\u00e9cheurs, et il mange avec eux ! \u00bb <\/strong><br \/>\n<strong>Alors J\u00e9sus leur dit cette parabole : <\/strong><br \/>\n<strong>\u00ab Si l\u2019un de vous a cent brebis et qu\u2019il en perd une, n\u2019abandonne-t-il pas les quatre-vingt-dix-neuf autres dans le d\u00e9sert pour aller chercher celle qui est perdue, jusqu\u2019\u00e0 ce qu\u2019il la retrouve ? <\/strong><br \/>\n<strong>Quand il l\u2019a retrouv\u00e9e, il la prend sur ses \u00e9paules, tout joyeux, <\/strong><br \/>\n<strong>et, de retour chez lui, il rassemble ses amis et ses voisins pour leur dire : \u201cR\u00e9jouissez-vous avec moi, car j\u2019ai retrouv\u00e9 ma brebis, celle qui \u00e9tait perdue !\u201d <\/strong><br \/>\n<strong>Je vous le dis : C\u2019est ainsi qu\u2019il y aura de la joie dans le ciel pour un seul p\u00e9cheur qui se convertit, plus que pour quatre-vingt-dix-neuf justes qui n\u2019ont pas besoin de conversion. <\/strong><br \/>\n<strong>Ou encore, si une femme a dix pi\u00e8ces d\u2019argent et qu\u2019elle en perd une, ne va-t-elle pas allumer une lampe, balayer la maison, et chercher avec soin jusqu\u2019\u00e0 ce qu\u2019elle la retrouve ? <\/strong><br \/>\n<strong>Quand elle l\u2019a retrouv\u00e9e, elle rassemble ses amies et ses voisines pour leur dire : \u201cR\u00e9jouissez-vous avec moi, car j\u2019ai retrouv\u00e9 la pi\u00e8ce d\u2019argent que j\u2019avais perdue !\u201d <\/strong><br \/>\n<strong>Ainsi je vous le dis : Il y a de la joie devant les anges de Dieu pour un seul p\u00e9cheur qui se convertit. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 15,1-10. En ce temps-l\u00e0, les publicains et les p\u00e9cheurs venaient tous \u00e0 J\u00e9sus pour l\u2019\u00e9couter. Les pharisiens et les scribes r\u00e9criminaient contre lui [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-34232","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=34232"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34232\/revisions"}],"predecessor-version":[{"id":34236,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34232\/revisions\/34236"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=34232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=34232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=34232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}