{"id":34217,"date":"2015-11-04T09:04:42","date_gmt":"2015-11-04T07:04:42","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=34217"},"modified":"2015-11-04T09:04:42","modified_gmt":"2015-11-04T07:04:42","slug":"enjil-al-yawm-por-041115","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-por-041115\/","title":{"rendered":"Enjil Al Yawm POR- 04\/11\/15"},"content":{"rendered":"<p><strong>Evangelho segundo S. Lucas 14,25-33. <\/strong><br \/>\n<strong>Naquele tempo, seguia Jesus uma grande multid\u00e3o. Jesus voltou-Se e disse-lhes:<\/strong><br \/>\n<strong>\u00abSe algu\u00e9m vem ter comigo, e n\u00e3o Me preferir ao pai, \u00e0 m\u00e3e, \u00e0 esposa, aos filhos, aos irm\u00e3os, \u00e0s irm\u00e3s e at\u00e9 \u00e0 pr\u00f3pria vida, n\u00e3o pode ser meu disc\u00edpulo. <\/strong><br \/>\n<strong>Quem n\u00e3o toma a sua cruz para Me seguir, n\u00e3o pode ser meu disc\u00edpulo. <\/strong><br \/>\n<strong>Quem de v\u00f3s, desejando construir uma torre, n\u00e3o se senta primeiro a calcular a despesa, para ver se tem com que termin\u00e1-la? <\/strong><br \/>\n<strong>N\u00e3o suceda que, depois de assentar os alicerces, se mostre incapaz de a concluir, e todos os que olharem comecem a fazer tro\u00e7a, dizendo: <\/strong><br \/>\n<strong>\u2018Esse homem come\u00e7ou a edificar, mas n\u00e3o foi capaz de concluir\u2019. <\/strong><br \/>\n<strong>E qual \u00e9 o rei que parte para a guerra contra outro rei e n\u00e3o se senta primeiro a considerar se \u00e9 capaz de se opor, com dez mil soldados, \u00e0quele que vem contra ele com vinte mil? <\/strong><br \/>\n<strong>Ali\u00e1s, enquanto o outro ainda est\u00e1 longe, manda-lhe uma delega\u00e7\u00e3o a pedir as condi\u00e7\u00f5es de paz. <\/strong><br \/>\n<strong>Assim, quem de entre v\u00f3s n\u00e3o renunciar a todos os seus bens, n\u00e3o pode ser meu disc\u00edpulo\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangelho segundo S. Lucas 14,25-33. Naquele tempo, seguia Jesus uma grande multid\u00e3o. Jesus voltou-Se e disse-lhes: \u00abSe algu\u00e9m vem ter comigo, e n\u00e3o Me preferir ao pai, \u00e0 m\u00e3e, \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-34217","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=34217"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34217\/revisions"}],"predecessor-version":[{"id":34222,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/34217\/revisions\/34222"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=34217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=34217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=34217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}