{"id":20429,"date":"2013-01-28T08:26:43","date_gmt":"2013-01-28T06:26:43","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20429"},"modified":"2013-01-28T08:26:43","modified_gmt":"2013-01-28T06:26:43","slug":"enjil-al-yawm-it-280113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-it-280113\/","title":{"rendered":"Enjil Al Yawm IT- 28\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Dal Vangelo di Ges\u00f9 Cristo secondo Marco 3,22-30. <\/strong><\/span><br \/>\n<strong>Ma gli scribi, che erano discesi da Gerusalemme, dicevano: \u00abCostui \u00e8 posseduto da Beelzeb\u00f9l e scaccia i dem\u00f2ni per mezzo del principe dei dem\u00f2ni\u00bb. <\/strong><br \/>\n<strong>Ma egli, chiamatili, diceva loro in parabole: \u00abCome pu\u00f2 satana scacciare satana? <\/strong><br \/>\n<strong>Se un regno \u00e8 diviso in se stesso, quel regno non pu\u00f2 reggersi; <\/strong><br \/>\n<strong>se una casa \u00e8 divisa in se stessa, quella casa non pu\u00f2 reggersi. <\/strong><br \/>\n<strong>Alla stessa maniera, se satana si ribella contro se stesso ed \u00e8 diviso, non pu\u00f2 resistere, ma sta per finire. <\/strong><br \/>\n<strong>Nessuno pu\u00f2 entrare nella casa di un uomo forte e rapire le sue cose se prima non avr\u00e0 legato l&#8217;uomo forte; allora ne sacchegger\u00e0 la casa. <\/strong><br \/>\n<strong>In verit\u00e0 vi dico: tutti i peccati saranno perdonati ai figli degli uomini e anche tutte le bestemmie che diranno; <\/strong><br \/>\n<strong>ma chi avr\u00e0 bestemmiato contro lo Spirito santo, non avr\u00e0 perdono in eterno: sar\u00e0 reo di colpa eterna\u00bb. <\/strong><br \/>\n<strong>Poich\u00e9 dicevano: \u00abE&#8217; posseduto da uno spirito immondo\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Vangelo di Ges\u00f9 Cristo secondo Marco 3,22-30. Ma gli scribi, che erano discesi da Gerusalemme, dicevano: \u00abCostui \u00e8 posseduto da Beelzeb\u00f9l e scaccia i dem\u00f2ni per mezzo del principe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20429","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20429"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20429\/revisions"}],"predecessor-version":[{"id":20439,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20429\/revisions\/20439"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}