{"id":20392,"date":"2013-01-26T12:17:48","date_gmt":"2013-01-26T10:17:48","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20392"},"modified":"2013-01-26T12:17:48","modified_gmt":"2013-01-26T10:17:48","slug":"enjil-al-yawm-it-260113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-it-260113\/","title":{"rendered":"Enjil Al Yawm IT- 26\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 10,1-9. <\/strong><\/span><br \/>\n<strong>Dopo questi fatti il Signore design\u00f2 altri settantadue discepoli e li invi\u00f2 a due a due avanti a s\u00e9 in ogni citt\u00e0 e luogo dove stava per recarsi. <\/strong><br \/>\n<strong>Diceva loro: \u00abLa messe \u00e8 molta, ma gli operai sono pochi. Pregate dunque il padrone della messe perch\u00e9 mandi operai per la sua messe. <\/strong><br \/>\n<strong>Andate: ecco io vi mando come agnelli in mezzo a lupi; <\/strong><br \/>\n<strong>non portate borsa, n\u00e9 bisaccia, n\u00e9 sandali e non salutate nessuno lungo la strada. <\/strong><br \/>\n<strong>In qualunque casa entriate, prima dite: Pace a questa casa. <\/strong><br \/>\n<strong>Se vi sar\u00e0 un figlio della pace, la vostra pace scender\u00e0 su di lui, altrimenti ritorner\u00e0 su di voi. <\/strong><br \/>\n<strong>Restate in quella casa, mangiando e bevendo di quello che hanno, perch\u00e9 l&#8217;operaio \u00e8 degno della sua mercede. Non passate di casa in casa. <\/strong><br \/>\n<strong>Quando entrerete in una citt\u00e0 e vi accoglieranno, mangiate quello che vi sar\u00e0 messo dinanzi, <\/strong><br \/>\n<strong>curate i malati che vi si trovano, e dite loro: Si \u00e8 avvicinato a voi il regno di Dio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 10,1-9. Dopo questi fatti il Signore design\u00f2 altri settantadue discepoli e li invi\u00f2 a due a due avanti a s\u00e9 in ogni citt\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20392","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20392"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20392\/revisions"}],"predecessor-version":[{"id":20401,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20392\/revisions\/20401"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}