{"id":20391,"date":"2013-01-26T12:17:34","date_gmt":"2013-01-26T10:17:34","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20391"},"modified":"2013-01-26T12:17:34","modified_gmt":"2013-01-26T10:17:34","slug":"enjil-al-yawm-fr-260113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-260113\/","title":{"rendered":"Enjil Al Yawm FR- 26\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>\u00c9vangile de J\u00e9sus Christ selon saint Luc 10,1-9. <\/strong><\/span><br \/>\n<strong>Parmi ses disciples, le Seigneur en d\u00e9signa encore soixante-douze, et il les envoya deux par deux devant lui dans toutes les villes et localit\u00e9s o\u00f9 lui-m\u00eame devait aller. <\/strong><br \/>\n<strong>Il leur dit : \u00ab La moisson est abondante, mais les ouvriers sont peu nombreux. Priez donc le ma\u00eetre de la moisson d&#8217;envoyer des ouvriers pour sa moisson. <\/strong><br \/>\n<strong>Allez ! Je vous envoie comme des agneaux au milieu des loups. <\/strong><br \/>\n<strong>N&#8217;emportez ni argent, ni sac, ni sandales, et ne vous attardez pas en salutations sur la route. <\/strong><br \/>\n<strong>Dans toute maison o\u00f9 vous entrerez, dites d&#8217;abord : &#8216;Paix \u00e0 cette maison. &#8216;<\/strong><br \/>\n<strong>S&#8217;il y a l\u00e0 un ami de la paix, votre paix ira reposer sur lui ; sinon, elle reviendra sur vous. <\/strong><br \/>\n<strong>Restez dans cette maison, mangeant et buvant ce que l&#8217;on vous servira ; car le travailleur m\u00e9rite son salaire. Ne passez pas de maison en maison. <\/strong><br \/>\n<strong>Dans toute ville o\u00f9 vous entrerez et o\u00f9 vous serez accueillis, mangez ce qu&#8217;on vous offrira. <\/strong><br \/>\n<strong>L\u00e0, gu\u00e9rissez les malades, et dites aux habitants : &#8216;Le r\u00e8gne de Dieu est tout proche de vous. &#8216;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Luc 10,1-9. Parmi ses disciples, le Seigneur en d\u00e9signa encore soixante-douze, et il les envoya deux par deux devant lui dans toutes les villes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20391","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20391"}],"version-history":[{"count":1,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20391\/revisions"}],"predecessor-version":[{"id":20397,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20391\/revisions\/20397"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}