{"id":20314,"date":"2013-01-22T08:48:10","date_gmt":"2013-01-22T06:48:10","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20314"},"modified":"2013-01-22T08:48:10","modified_gmt":"2013-01-22T06:48:10","slug":"enjil-al-yawm-fr-220113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-fr-220113\/","title":{"rendered":"Enjil Al Yawm FR- 22\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>\u00c9vangile de J\u00e9sus Christ selon saint Marc 2,23-28. <\/strong><\/span><br \/>\n<strong>Un jour de sabbat, J\u00e9sus marchait \u00e0 travers les champs de bl\u00e9 ; et ses disciples, chemin faisant, se mirent \u00e0 arracher des \u00e9pis. <\/strong><br \/>\n<strong>Les pharisiens lui disaient : \u00ab Regarde ce qu&#8217;ils font le jour du sabbat ! Cela n&#8217;est pas permis. \u00bb <\/strong><br \/>\n<strong>J\u00e9sus leur r\u00e9pond : \u00ab N&#8217;avez-vous jamais lu ce que fit David, lorsqu&#8217;il fut dans le besoin et qu&#8217;il eut faim, lui et ses compagnons ? <\/strong><br \/>\n<strong>Au temps du grand pr\u00eatre Abiathar, il entra dans la maison de Dieu et mangea les pains de l&#8217;offrande que seuls les pr\u00eatres peuvent manger, et il en donna aussi \u00e0 ses compagnons. \u00bb <\/strong><br \/>\n<strong>Il leur disait encore : \u00ab Le sabbat a \u00e9t\u00e9 fait pour l&#8217;homme, et non pas l&#8217;homme pour le sabbat. <\/strong><br \/>\n<strong>Voil\u00e0 pourquoi le Fils de l&#8217;homme est ma\u00eetre, m\u00eame du sabbat. \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vangile de J\u00e9sus Christ selon saint Marc 2,23-28. Un jour de sabbat, J\u00e9sus marchait \u00e0 travers les champs de bl\u00e9 ; et ses disciples, chemin faisant, se mirent \u00e0 arracher [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20314","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20314"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20314\/revisions"}],"predecessor-version":[{"id":20324,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20314\/revisions\/20324"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}