{"id":20112,"date":"2013-01-08T12:13:09","date_gmt":"2013-01-08T10:13:09","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20112"},"modified":"2013-01-08T12:13:09","modified_gmt":"2013-01-08T10:13:09","slug":"enjil-al-yawm-es-080113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-es-080113\/","title":{"rendered":"Enjil Al Yawm ES- 08\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Evangelio seg\u00fan San Marcos 6,34-44. <\/strong><\/span><br \/>\n<strong>Al desembarcar, Jes\u00fas vio una gran muchedumbre y se compadeci\u00f3 de ella, porque eran como ovejas sin pastor, y estuvo ense\u00f1\u00e1ndoles largo rato. <\/strong><br \/>\n<strong>Como se hab\u00eda hecho tarde, sus disc\u00edpulos se acercaron y le dijeron: &#8220;Este es un lugar desierto, y ya es muy tarde. <\/strong><br \/>\n<strong>Despide a la gente, para que vaya a las poblaciones cercanas a comprar algo para comer&#8221;. <\/strong><br \/>\n<strong>El respondi\u00f3: &#8220;Denles de comer ustedes mismos&#8221;. Ellos le dijeron: &#8220;Habr\u00eda que comprar pan por valor de doscientos denarios para dar de comer a todos&#8221;. <\/strong><br \/>\n<strong>Jes\u00fas pregunt\u00f3: &#8220;\u00bfCu\u00e1ntos panes tienen ustedes? Vayan a ver&#8221;. Despu\u00e9s de averiguarlo, dijeron: &#8220;Cinco panes y dos pescados&#8221;. <\/strong><br \/>\n<strong>El les orden\u00f3 que hicieran sentar a todos en grupos, sobre la hierba verde, <\/strong><br \/>\n<strong>y la gente se sent\u00f3 en grupos de cien y de cincuenta. <\/strong><br \/>\n<strong>Entonces \u00e9l tom\u00f3 los cinco panes y los dos pescados, y levantando los ojos al cielo, pronunci\u00f3 la bendici\u00f3n, parti\u00f3 los panes y los fue entregando a sus disc\u00edpulos para que los distribuyeran. Tambi\u00e9n reparti\u00f3 los dos pescados entre la gente. <\/strong><br \/>\n<strong>Todos comieron hasta saciarse, <\/strong><br \/>\n<strong>y se recogieron doce canastas llenas de sobras de pan y de restos de pescado. <\/strong><br \/>\n<strong>Los que comieron eran cinco mil hombres.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangelio seg\u00fan San Marcos 6,34-44. Al desembarcar, Jes\u00fas vio una gran muchedumbre y se compadeci\u00f3 de ella, porque eran como ovejas sin pastor, y estuvo ense\u00f1\u00e1ndoles largo rato. Como se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20112","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20112"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20112\/revisions"}],"predecessor-version":[{"id":20124,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20112\/revisions\/20124"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}