{"id":20020,"date":"2013-01-03T09:35:51","date_gmt":"2013-01-03T07:35:51","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=20020"},"modified":"2013-01-03T09:35:51","modified_gmt":"2013-01-03T07:35:51","slug":"enjil-al-yawm-por-030113","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-por-030113\/","title":{"rendered":"Enjil Al Yawm POR- 03\/01\/13"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Evangelho segundo S. Jo\u00e3o 1,29-34. <\/strong><\/span><br \/>\n<strong>No dia seguinte ao sei primeiro testemunho, Jo\u00e3o Baptista viu Jesus, que vinha ao seu encontro, e exclamou: \u00abEis o Cordeiro de Deus, que tira o pecado do mundo! <\/strong><br \/>\n<strong>\u00c9 aquele de quem eu disse: &#8216;Depois de mim vem um homem que me passou \u00e0 frente, porque existia antes de mim.&#8217; <\/strong><br \/>\n<strong>Eu n\u00e3o o conhecia bem; mas foi para Ele se manifestar a Israel que eu vim baptizar com \u00e1gua.\u00bb <\/strong><br \/>\n<strong>E Jo\u00e3o testemunhou: \u00abVi o Esp\u00edrito que descia do c\u00e9u como uma pomba e permanecia sobre Ele. <\/strong><br \/>\n<strong>E eu n\u00e3o o conhecia, mas quem me enviou a baptizar com \u00e1gua \u00e9 que me disse: &#8216;Aquele sobre quem vires descer o Esp\u00edrito e poisar sobre Ele, \u00e9 o que baptiza com o Esp\u00edrito Santo&#8217;. <\/strong><br \/>\n<strong>Pois bem: eu vi e dou testemunho de que este \u00e9 o Filho de Deus.\u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangelho segundo S. Jo\u00e3o 1,29-34. No dia seguinte ao sei primeiro testemunho, Jo\u00e3o Baptista viu Jesus, que vinha ao seu encontro, e exclamou: \u00abEis o Cordeiro de Deus, que tira [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-20020","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=20020"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20020\/revisions"}],"predecessor-version":[{"id":20031,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/20020\/revisions\/20031"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=20020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=20020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=20020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}