{"id":19914,"date":"2012-12-29T09:01:49","date_gmt":"2012-12-29T07:01:49","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=19914"},"modified":"2012-12-29T09:01:49","modified_gmt":"2012-12-29T07:01:49","slug":"enjil-al-yawm-it-291212","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/enjil\/enjil-al-yawm-it-291212\/","title":{"rendered":"Enjil Al Yawm IT- 29\/12\/12"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 2,22-35. <\/strong><\/span><br \/>\n<strong>Quando venne il tempo della loro purificazione secondo la Legge di Mos\u00e8, portarono il bambino a Gerusalemme per offrirlo al Signore, <\/strong><br \/>\n<strong>come \u00e8 scritto nella Legge del Signore: ogni maschio primogenito sar\u00e0 sacro al Signore; <\/strong><br \/>\n<strong>e per offrire in sacrificio una coppia di tortore o di giovani colombi, come prescrive la Legge del Signore. <\/strong><br \/>\n<strong>Ora a Gerusalemme c&#8217;era un uomo di nome Simeone, uomo giusto e timorato di Dio, che aspettava il conforto d&#8217;Israele; <\/strong><br \/>\n<strong>lo Spirito Santo che era sopra di lui, gli aveva preannunziato che non avrebbe visto la morte senza prima aver veduto il Messia del Signore. <\/strong><br \/>\n<strong>Mosso dunque dallo Spirito, si rec\u00f2 al tempio; e mentre i genitori vi portavano il bambino Ges\u00f9 per adempiere la Legge, <\/strong><br \/>\n<strong>lo prese tra le braccia e benedisse Dio: <\/strong><br \/>\n<strong>\u00abOra lascia, o Signore, che il tuo servo vada in pace secondo la tua parola; <\/strong><br \/>\n<strong>perch\u00e9 i miei occhi han visto la tua salvezza, <\/strong><br \/>\n<strong>preparata da te davanti a tutti i popoli, <\/strong><br \/>\n<strong>luce per illuminare le genti e gloria del tuo popolo Israele\u00bb. <\/strong><br \/>\n<strong>Il padre e la madre di Ges\u00f9 si stupivano delle cose che si dicevano di lui. <\/strong><br \/>\n<strong>Simeone li benedisse e parl\u00f2 a Maria, sua madre: \u00abEgli \u00e8 qui per la rovina e la risurrezione di molti in Israele, segno di contraddizione <\/strong><br \/>\n<strong>perch\u00e9 siano svelati i pensieri di molti cuori. E anche a te una spada trafigger\u00e0 l&#8217;anima\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Vangelo di Ges\u00f9 Cristo secondo Luca 2,22-35. Quando venne il tempo della loro purificazione secondo la Legge di Mos\u00e8, portarono il bambino a Gerusalemme per offrirlo al Signore, come [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-19914","post","type-post","status-publish","format-standard","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/19914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=19914"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/19914\/revisions"}],"predecessor-version":[{"id":19924,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/19914\/revisions\/19924"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=19914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=19914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=19914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}