{"id":14687,"date":"2012-04-17T10:58:35","date_gmt":"2012-04-17T08:58:35","guid":{"rendered":"http:\/\/www.lebanesesaints.com\/Home\/?p=14687"},"modified":"2012-04-17T10:58:35","modified_gmt":"2012-04-17T08:58:35","slug":"enjil-al-yawm-por-170412","status":"publish","type":"post","link":"https:\/\/www.lebanesesaints.com\/Home\/uncategorized\/enjil-al-yawm-por-170412\/","title":{"rendered":"Enjil Al Yawm POR- 17\/04\/12"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Evangelho segundo S. Jo\u00e3o 3,7b-15.<\/strong><\/span><br \/>\n<strong>Naquele tempo, disse Jesus a Nicodemos: \u00abN\u00e3o te admires por Eu te ter dito: &#8216;V\u00f3s tendes de nascer do Alto.&#8217;<\/strong><br \/>\n<strong>O vento sopra onde quer e tu ouves a sua voz, mas n\u00e3o sabes de onde vem nem para onde vai. Assim acontece com todo aquele que nasceu do Esp\u00edrito.\u00bb<\/strong><br \/>\n<strong>Nicodemos interveio e disse-lhe: \u00abComo pode ser isso?\u00bb<\/strong><br \/>\n<strong>Jesus respondeu-lhe: \u00abTu \u00e9s mestre em Israel e n\u00e3o sabes estas coisas?<\/strong><br \/>\n<strong>Em verdade, em verdade te digo: n\u00f3s falamos do que sabemos e damos testemunho do que vimos, mas v\u00f3s n\u00e3o aceitais o nosso testemunho.<\/strong><br \/>\n<strong>Se vos falei das coisas da terra e n\u00e3o credes, como \u00e9 que haveis de crer quando vos falar das coisas do C\u00e9u?<\/strong><br \/>\n<strong>Pois ningu\u00e9m subiu ao C\u00e9u a n\u00e3o ser aquele que desceu do C\u00e9u, o Filho do Homem.<\/strong><br \/>\n<strong>Assim como Mois\u00e9s ergueu a serpente no deserto, assim tamb\u00e9m \u00e9 necess\u00e1rio que o Filho do Homem seja erguido ao alto,<\/strong><br \/>\n<strong>a fim de que todo o que nele cr\u00ea tenha a vida eterna. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangelho segundo S. Jo\u00e3o 3,7b-15. Naquele tempo, disse Jesus a Nicodemos: \u00abN\u00e3o te admires por Eu te ter dito: &#8216;V\u00f3s tendes de nascer do Alto.&#8217; O vento sopra onde quer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-14687","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/14687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/comments?post=14687"}],"version-history":[{"count":2,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/14687\/revisions"}],"predecessor-version":[{"id":14696,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/posts\/14687\/revisions\/14696"}],"wp:attachment":[{"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/media?parent=14687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/categories?post=14687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebanesesaints.com\/Home\/wp-json\/wp\/v2\/tags?post=14687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}